{"id":2500,"date":"2023-05-04T15:16:18","date_gmt":"2023-05-04T18:16:18","guid":{"rendered":"https:\/\/avantimkt.com.br\/siteantigo\/?p=2500"},"modified":"2023-05-25T15:12:09","modified_gmt":"2023-05-25T18:12:09","slug":"voce-costuma-ligar-a-sua-camera-nas-reunioes-virtuais-conheca-os-beneficios-dessa-pratica","status":"publish","type":"post","link":"https:\/\/avantimkt.com.br\/siteantigo\/dicas\/voce-costuma-ligar-a-sua-camera-nas-reunioes-virtuais-conheca-os-beneficios-dessa-pratica\/","title":{"rendered":"Voc\u00ea costuma ligar a sua c\u00e2mera nas reuni\u00f5es virtuais? Conhe\u00e7a os benef\u00edcios dessa pr\u00e1tica."},"content":{"rendered":"<p>As reuni\u00f5es virtuais vieram para ficar. O que antes parecia ser somente uma forma de contornar os efeitos do lockdown na pandemia se mostrou uma maneira bastante eficaz de conectar pessoas sem a necessidade de deslocamento. Mais um ponto positivo para a tecnologia!<\/p>\n<p>Com as intera\u00e7\u00f5es online se tornando cada vez mais comuns, aparecem novas quest\u00f5es, como a decis\u00e3o de ligar ou n\u00e3o a c\u00e2mera durante as confer\u00eancias. Mesmo que voc\u00ea n\u00e3o se sinta muito confort\u00e1vel em frente \u00e0 webcam, vamos te mostrar porque, em muitos momentos, habilitar o v\u00eddeo pode ser bom para voc\u00ea, seus colegas e, ainda, facilitar a condu\u00e7\u00e3o da reuni\u00e3o. Confira:<\/p>\n<p>&nbsp;<\/p>\n<h3>Promove a conex\u00e3o entre os participantes<\/h3>\n<p>Manter a c\u00e2mera ligada mostra que voc\u00ea est\u00e1 interessado, engajado e atento ao assunto da reuni\u00e3o, o que colabora para gerar v\u00ednculos e fortalecer o pertencimento. Esse gesto tamb\u00e9m demonstra respeito por quem marcou o call e envolvimento com o tema. Por outro lado, manter a webcam desligada durante todos os encontros online pode indicar desconex\u00e3o.<\/p>\n<p>Sem contar que as intera\u00e7\u00f5es e conversas por v\u00eddeo contribuem para fortalecer a integra\u00e7\u00e3o, especialmente em equipes em trabalho remoto, e reduzem a sensa\u00e7\u00e3o de isolamento.<\/p>\n<p>&nbsp;<\/p>\n<h3>Facilita a comunica\u00e7\u00e3o<\/h3>\n<p>Ao ver as pessoas, voc\u00ea consegue captar sinais n\u00e3o verbais, o que \u00e9 essencial para estabelecer a comunica\u00e7\u00e3o, al\u00e9m de um indicador importante para o facilitador da videoconfer\u00eancia.<\/p>\n<p>Afinal, todos os nossos comportamentos, como postura corporal, express\u00f5es faciais, contato visual, gestos com as m\u00e3os e tom de voz contribuem para melhorar a forma como nos comunicamos e nos entendemos. Essa intera\u00e7\u00e3o \u00e9 fundamental para transmitir a mensagem com clareza e, ainda, evita interpreta\u00e7\u00f5es equivocadas.<\/p>\n<p>&nbsp;<\/p>\n<h3>Incentiva o engajamento<\/h3>\n<p>Estabelecer contato visual com as pessoas favorece a intera\u00e7\u00e3o e a participa\u00e7\u00e3o nos debates, o que resulta em conversas mais reais e reuni\u00f5es mais produtivas. Se voc\u00ea \u00e9 multitarefa, manter a c\u00e2mera ligada tamb\u00e9m pode ajudar a te manter focado nos objetivos da reuni\u00e3o e n\u00e3o em outros afazeres, como verificar e-mails ou responder mensagens no celular.<\/p>\n<p>A aten\u00e7\u00e3o plena \u00e9 muito importante para a compreens\u00e3o da mensagem, al\u00e9m de contribuir para o surgimento de insights e novas ideias.<\/p>\n<p>&nbsp;<\/p>\n<p>Leia tamb\u00e9m: <a title=\"Comunica\u00e7\u00e3o Emp\u00e1tica e seus benef\u00edcios para o Atendimento ao Cliente\" href=\"https:\/\/avantimkt.com.br\/siteantigo\/tendencias\/comunicacao-empatica-e-seus-beneficios-para-o-atendimento-ao-cliente\/\">Comunica\u00e7\u00e3o Emp\u00e1tica e seus benef\u00edcios para o Atendimento ao Cliente<\/a><\/p>\n<p>&nbsp;<\/p>\n<h3>Favorece a sua confian\u00e7a<\/h3>\n<p>Os encontros online possuem uma atmosfera diferente das conversas presenciais, o que pode atrapalhar seu fluxo se voc\u00ea for liderar uma reuni\u00e3o. Neste sentido, ligar a c\u00e2mera \u00e9 uma forma de afirmar sua confian\u00e7a e lideran\u00e7a. Isso te auxiliar\u00e1 a conduzir as conversas com muito mais facilidade.<\/p>\n<p>&nbsp;<\/p>\n<h3>Aumenta a sua visibilidade<\/h3>\n<p>Para alguns casos, vale a m\u00e1xima: quem n\u00e3o \u00e9 visto n\u00e3o \u00e9 lembrado. Nossa mem\u00f3ria visual \u00e9 muito forte, portanto ao n\u00e3o compartilhar seu v\u00eddeo, em uma reuni\u00e3o h\u00edbrida<br \/>\n(com pessoas participando online e outras presencialmente), por exemplo, voc\u00ea ficar\u00e1 praticamente invis\u00edvel.<\/p>\n<p>Isso dificulta que os outros participantes se lembrem de te envolver nas discuss\u00f5es ou, at\u00e9 mesmo, se recordem que voc\u00ea esteve efetivamente na conversa.<\/p>\n<p>&nbsp;<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-2510 size-full\" src=\"https:\/\/avantimkt.com.br\/siteantigo\/wp-content\/uploads\/2023\/05\/Voce-costuma-ligar-a-sua-camera-nas-reunioes-virtuais-2.jpg\" alt=\"Voc\u00ea costuma ligar a sua c\u00e2mera nas reuni\u00f5es virtuais\" width=\"1280\" height=\"720\" srcset=\"https:\/\/avantimkt.com.br\/siteantigo\/wp-content\/uploads\/2023\/05\/Voce-costuma-ligar-a-sua-camera-nas-reunioes-virtuais-2.jpg 1280w, https:\/\/avantimkt.com.br\/siteantigo\/wp-content\/uploads\/2023\/05\/Voce-costuma-ligar-a-sua-camera-nas-reunioes-virtuais-2-300x169.jpg 300w, https:\/\/avantimkt.com.br\/siteantigo\/wp-content\/uploads\/2023\/05\/Voce-costuma-ligar-a-sua-camera-nas-reunioes-virtuais-2-1024x576.jpg 1024w, https:\/\/avantimkt.com.br\/siteantigo\/wp-content\/uploads\/2023\/05\/Voce-costuma-ligar-a-sua-camera-nas-reunioes-virtuais-2-768x432.jpg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/p>\n<p>&nbsp;<\/p>\n<h3>Equil\u00edbrio \u00e9 tudo<\/h3>\n<p>Quem participa de muitas reuni\u00f5es online diariamente sabe o quanto isso pode ser cansativo. Ficar muito tempo exposto \u00e0s telas e confer\u00eancias pode causar a chamada <a href=\"https:\/\/lemanncenter.stanford.edu\/media\/fadiga-de-zoom-o-brasileiro-est%C3%A1-exausto-de-videochamadas\" target=\"_blank\" rel=\"noopener\">fadiga de zoom<\/a>, levando ao esgotamento mental.<\/p>\n<p>Uma dica v\u00e1lida para diminuir o cansa\u00e7o nos encontros virtuais \u00e9 desabilitar a autovisualiza\u00e7\u00e3o. Querendo ou n\u00e3o, acabamos checando nossa apar\u00eancia e nossas rea\u00e7\u00f5es no v\u00eddeo em muitos momentos, o que contribui com a fadiga.<\/p>\n<p>Em suma, o importante \u00e9 prezar pelo equil\u00edbrio e, sobretudo, pelo bom senso. Respeite os seus limites e escolha as reuni\u00f5es nas quais \u00e9 mais importante a sua participa\u00e7\u00e3o com a c\u00e2mera ligada.<\/p>\n<p>&nbsp;<\/p>\n<h4>Conhe\u00e7a algumas dicas:<\/h4>\n<p><strong>Mantenha a c\u00e2mera ligada quando voc\u00ea:<\/strong><\/p>\n<ul>\n<li>\u00c9 o facilitador da reuni\u00e3o<\/li>\n<li>\u00c9 a primeira vez que conhece as pessoas<\/li>\n<li>Quer se conectar com os participantes e demonstrar interesse no assunto<\/li>\n<li>Se sente confort\u00e1vel consigo mesmo e com o ambiente a sua volta<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><strong>Tudo bem desligar a webcam quando voc\u00ea:<\/strong><\/p>\n<ul>\n<li>Est\u00e1 participando como ouvinte<\/li>\n<li>J\u00e1 interagiu com as mesmas pessoas em outros momentos do dia e est\u00e1 cansado<\/li>\n<li>Est\u00e1 em um ambiente desfavor\u00e1vel (bagun\u00e7a, obras, luminosidade prejudicada, presen\u00e7a de outras pessoas, distra\u00e7\u00f5es, entre outros)<\/li>\n<li>Est\u00e1 com a conex\u00e3o de internet ruim<\/li>\n<li>Est\u00e1 mentalmente esgotado<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Gostou do conte\u00fado? Confira mais artigos no nosso <a href=\"https:\/\/avantimkt.com.br\/siteantigo\/blog\/\">blog<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mesmo que voc\u00ea n\u00e3o se sinta confort\u00e1vel em frente \u00e0 webcam, vamos mostrar porque habilitar o v\u00eddeo pode ser bom para voc\u00ea e sua equipe durante as suas reuni\u00f5es.<\/p>\n","protected":false},"author":3,"featured_media":2502,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[51,50,48,49,53,52],"class_list":["post-2500","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dicas","tag-google-meet","tag-meet","tag-reuniao-virtual","tag-reunioes-virtuais","tag-video-chamadas","tag-vioconferencia"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/avantimkt.com.br\/siteantigo\/wp-json\/wp\/v2\/posts\/2500","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/avantimkt.com.br\/siteantigo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/avantimkt.com.br\/siteantigo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/avantimkt.com.br\/siteantigo\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/avantimkt.com.br\/siteantigo\/wp-json\/wp\/v2\/comments?post=2500"}],"version-history":[{"count":0,"href":"https:\/\/avantimkt.com.br\/siteantigo\/wp-json\/wp\/v2\/posts\/2500\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/avantimkt.com.br\/siteantigo\/wp-json\/wp\/v2\/media\/2502"}],"wp:attachment":[{"href":"https:\/\/avantimkt.com.br\/siteantigo\/wp-json\/wp\/v2\/media?parent=2500"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/avantimkt.com.br\/siteantigo\/wp-json\/wp\/v2\/categories?post=2500"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/avantimkt.com.br\/siteantigo\/wp-json\/wp\/v2\/tags?post=2500"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}